{"id":56,"count":1,"description":"","link":"https:\/\/storycase.co.uk\/radio\/category\/video-games\/","name":"Video Games","slug":"video-games","taxonomy":"category","parent":0,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Video Games Archives - Radio Retro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/storycase.co.uk\/radio\/category\/video-games\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Video Games Archives - Radio Retro\" \/>\n<meta property=\"og:url\" content=\"https:\/\/storycase.co.uk\/radio\/category\/video-games\/\" \/>\n<meta property=\"og:site_name\" content=\"Radio Retro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/storycase.co.uk\\\/radio\\\/category\\\/video-games\\\/\",\"url\":\"https:\\\/\\\/storycase.co.uk\\\/radio\\\/category\\\/video-games\\\/\",\"name\":\"Video Games Archives - Radio Retro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/storycase.co.uk\\\/radio\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/storycase.co.uk\\\/radio\\\/category\\\/video-games\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/storycase.co.uk\\\/radio\\\/category\\\/video-games\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/storycase.co.uk\\\/radio\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Video Games\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/storycase.co.uk\\\/radio\\\/#website\",\"url\":\"https:\\\/\\\/storycase.co.uk\\\/radio\\\/\",\"name\":\"Radio Retro\",\"description\":\"Don&#039;t throw it away!\",\"publisher\":{\"@id\":\"https:\\\/\\\/storycase.co.uk\\\/radio\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/storycase.co.uk\\\/radio\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/storycase.co.uk\\\/radio\\\/#organization\",\"name\":\"Radio Retro\",\"url\":\"https:\\\/\\\/storycase.co.uk\\\/radio\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/storycase.co.uk\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/storycase.co.uk\\\/radio\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/IMG_0324.jpg\",\"contentUrl\":\"https:\\\/\\\/storycase.co.uk\\\/radio\\\/wp-content\\\/uploads\\\/2014\\\/11\\\/IMG_0324.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Radio Retro\"},\"image\":{\"@id\":\"https:\\\/\\\/storycase.co.uk\\\/radio\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Video Games Archives - Radio Retro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/storycase.co.uk\/radio\/category\/video-games\/","og_locale":"en_GB","og_type":"article","og_title":"Video Games Archives - Radio Retro","og_url":"https:\/\/storycase.co.uk\/radio\/category\/video-games\/","og_site_name":"Radio Retro","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/storycase.co.uk\/radio\/category\/video-games\/","url":"https:\/\/storycase.co.uk\/radio\/category\/video-games\/","name":"Video Games Archives - Radio Retro","isPartOf":{"@id":"https:\/\/storycase.co.uk\/radio\/#website"},"breadcrumb":{"@id":"https:\/\/storycase.co.uk\/radio\/category\/video-games\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/storycase.co.uk\/radio\/category\/video-games\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/storycase.co.uk\/radio\/"},{"@type":"ListItem","position":2,"name":"Video Games"}]},{"@type":"WebSite","@id":"https:\/\/storycase.co.uk\/radio\/#website","url":"https:\/\/storycase.co.uk\/radio\/","name":"Radio Retro","description":"Don&#039;t throw it away!","publisher":{"@id":"https:\/\/storycase.co.uk\/radio\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/storycase.co.uk\/radio\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/storycase.co.uk\/radio\/#organization","name":"Radio Retro","url":"https:\/\/storycase.co.uk\/radio\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/storycase.co.uk\/radio\/#\/schema\/logo\/image\/","url":"https:\/\/storycase.co.uk\/radio\/wp-content\/uploads\/2014\/11\/IMG_0324.jpg","contentUrl":"https:\/\/storycase.co.uk\/radio\/wp-content\/uploads\/2014\/11\/IMG_0324.jpg","width":1200,"height":800,"caption":"Radio Retro"},"image":{"@id":"https:\/\/storycase.co.uk\/radio\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/storycase.co.uk\/radio\/wp-json\/wp\/v2\/categories\/56","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/storycase.co.uk\/radio\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/storycase.co.uk\/radio\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/storycase.co.uk\/radio\/wp-json\/wp\/v2\/posts?categories=56"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}